{"id":20574,"date":"2026-08-02T20:55:44","date_gmt":"2026-08-02T20:55:44","guid":{"rendered":"https:\/\/jerseys-dev.sizesall.us\/de\/?page_id=20574"},"modified":"2026-08-06T13:33:28","modified_gmt":"2026-08-06T13:33:28","slug":"privacy-policy","status":"publish","type":"page","link":"https:\/\/kryemo.com\/de\/privacy-policy\/","title":{"rendered":"Datenschutzrichtlinie"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"20574\" class=\"elementor elementor-20574\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-8143ae9 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8143ae9\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e74a8c4\" data-id=\"e74a8c4\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4d6d070 elementor-widget elementor-widget-html\" data-id=\"4d6d070\" data-element_type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t\t<p><strong>Zuletzt aktualisiert: 23 July 2026<\/strong><\/p>\n\n<p>Diese Datenschutzrichtlinie erkl\u00e4rt, was mit personenbezogenen Daten geschieht, die Sie uns mitteilen oder die wir \u00fcber Sie erheben, beobachten und\/oder ableiten k\u00f6nnen, wenn Sie unsere Website und damit verbundene Dienste (unsere \u201eAngebote\u201c) nutzen. Bei Fragen kontaktieren Sie uns unter <a href=\"mailto:&#105;&#110;&#102;o&#64;k&#114;ye&#109;&#111;.c&#111;&#109;\">info@kryemo.com<\/a>.<\/p>\n\n<p>Diese Datenschutzrichtlinie gilt f\u00fcr personenbezogene Daten, die von oder im Auftrag von <strong>KRYEMO<\/strong> verarbeitet werden \u2013 von Besuchern unserer Website und anderer Angebote oder wie sonst in dieser Richtlinie beschrieben.<\/p>\n\n<p><strong>Inhaltsverzeichnis<\/strong><\/p>\n<ol>\n\t<li><a href=\"#about-us\">\u00dcber uns und Kontakt<\/a><\/li>\n\t<li><a href=\"#what-we-process\">Welche personenbezogenen Daten verarbeiten wir und woher stammen sie?<\/a><\/li>\n\t<li><a href=\"#how-we-use\">Wie verwenden wir Ihre personenbezogenen Daten?<\/a><\/li>\n\t<li><a href=\"#your-rights\">Welche Rechte haben Sie und wie \u00fcben Sie sie aus?<\/a><\/li>\n\t<li><a href=\"#third-party\">Websites und Social-Media-Dienste Dritter<\/a><\/li>\n\t<li><a href=\"#children\">Daten von Minderj\u00e4hrigen<\/a><\/li>\n\t<li><a href=\"#social\">Social Media, Widgets und offene Foren<\/a><\/li>\n\t<li><a href=\"#sharing\">An wen geben wir personenbezogene Daten weiter?<\/a><\/li>\n\t<li><a href=\"#retention\">Wie lange speichern wir Ihre Daten?<\/a><\/li>\n\t<li><a href=\"#updates\">Aktualisierungen dieser Datenschutzrichtlinie<\/a><\/li>\n<\/ol>\n\n<p id=\"about-us\"><strong>1. \u00dcber uns und Kontakt<\/strong><\/p>\n<p>Wir sind <strong>KRYEMO<\/strong> (Putian Licheng Kuliu Liao Trading Co., Ltd.), der Verantwortliche f\u00fcr die Verarbeitung Ihrer personenbezogenen Daten von Besuchern unserer Website und anderer Angebote. Sie erreichen uns unter <a href=\"mailto:info&#64;&#107;&#114;y&#101;&#109;o.com\">info@kryemo.com<\/a>. Unsere Anschrift: No. 45 Fengtuo, Baosheng Village, Xindu Town, Licheng District, Putian City, Fujian Province, Postcode 351142.<\/p>\n\n<p id=\"what-we-process\"><strong>2. Welche personenbezogenen Daten verarbeiten wir und woher stammen sie?<\/strong><\/p>\n\n<p><strong>Quellen der personenbezogenen Daten<\/strong><\/p>\n<p>Wir erheben Informationen, wenn Sie unsere Website besuchen, ein Konto erstellen, Produkte kaufen, uns per E-Mail oder Kontaktformular kontaktieren, eine Mitteilung von uns erhalten oder anderweitig mit uns interagieren (einschlie\u00dflich \u00fcber Social Media oder Werbung).<\/p>\n<p>Wir k\u00f6nnen \u2013 soweit gesetzlich zul\u00e4ssig \u2013 auch Informationen von Dienstleistern, Zahlungsanbietern, Werbepartnern, Analyseanbietern, \u00f6ffentlichen Quellen und Social-Media-Plattformen erhalten.<\/p>\n<p>Sie sind nicht verpflichtet, uns personenbezogene Daten mitzuteilen; ohne bestimmte Angaben (z.&nbsp;B. Transaktions- oder Kontaktdaten) k\u00f6nnen wir Ihre Bestellung oder angeforderte Leistungen jedoch m\u00f6glicherweise nicht erbringen.<\/p>\n<p>Wir k\u00f6nnen Informationen aus verschiedenen Quellen kombinieren und daraus R\u00fcckschl\u00fcsse ziehen, um ein Profil Ihrer Pr\u00e4ferenzen und Merkmale zu erstellen.<\/p>\n\n<p><strong>Kategorien personenbezogener Daten<\/strong><\/p>\n<ul>\n\t<li><strong>Kontaktdaten:<\/strong> Name, E-Mail-Adresse, Telefonnummer sowie Rechnungs-\/Lieferadresse.<\/li>\n\t<li><strong>Transaktionsdaten:<\/strong> Kaufdetails, Lieferdaten, Zahlungsdaten (\u00fcber unsere Zahlungsanbieter), Bestellhistorie, R\u00fcckgabe-\/Umtauschinformationen und zugeh\u00f6rige Kommunikation.<\/li>\n\t<li><strong>Rechtsbezogene Daten:<\/strong> Betrugspr\u00fcfungen oder -hinweise, Zahlungsablehnungen, Beschwerden und deren Bearbeitung sowie beh\u00f6rdliche Anfragen.<\/li>\n\t<li><strong>Pr\u00e4ferenzdaten:<\/strong> Marketingeinstellungen, Kontoeinstellungen, Wunschliste\/Vergleich sowie beobachtete oder abgeleitete Pr\u00e4ferenzen (z.&nbsp;B. Produkt- oder Teaminteressen).<\/li>\n\t<li><strong>Kommunikation:<\/strong> E-Mails, Kontaktformularnachrichten und sonstiger Schriftverkehr mit uns.<\/li>\n\t<li><strong>Kontodaten:<\/strong> Name, Passwort, Konto-ID und weitere mit Ihrem Konto verkn\u00fcpfte Informationen.<\/li>\n\t<li><strong>Freiwillig bereitgestellte Daten:<\/strong> z.&nbsp;B. Umfrageantworten, Gewinnspieleintr\u00e4ge, Lieblingsteams\/-spieler oder Gr\u00f6\u00dfenpr\u00e4ferenzen.<\/li>\n\t<li><strong>Beobachtete Daten:<\/strong> Online-Aktivit\u00e4t, die automatisch erfasst wird, wenn Sie unsere Angebote nutzen \u2013 einschlie\u00dflich besuchter Seiten, angesehener Produkte, Ger\u00e4te-\/Browserdaten, IP-Adresse, ungef\u00e4hre Standortangaben, Cookie- und Werbekennungen sowie Interaktionen mit E-Mails oder Anzeigen. Details finden Sie in unserer <a href=\"\/cookie-policy\/\">Cookie-Richtlinie<\/a>.<\/li>\n<\/ul>\n\n<p id=\"how-we-use\"><strong>3. Wie verwenden wir Ihre personenbezogenen Daten?<\/strong><\/p>\n<p>Wir verwenden Ihre Daten f\u00fcr verschiedene Zwecke. Die Datenschutzgesetze des Vereinigten K\u00f6nigreichs\/der EU sehen bestimmte Rechtsgrundlagen vor. Die wichtigsten Zwecke und Grundlagen sind:<\/p>\n<ul>\n\t<li><strong>Einwilligung:<\/strong> Marketing per E-Mail\/SMS oder andere Direktwerbung, soweit erforderlich; Benachrichtigungen (z.&nbsp;B. wieder verf\u00fcgbar), die Sie anfordern; sowie bestimmte Cookies\/Tracking-Technologien, soweit Einwilligung erforderlich ist. Sie k\u00f6nnen die Einwilligung jederzeit widerrufen oder sich abmelden.<\/li>\n\t<li><strong>Vertragserf\u00fcllung:<\/strong> Erstellung und Verwaltung Ihres Kontos; Bearbeitung und Erf\u00fcllung von Bestellungen; Zahlungsabwicklung; Versand; Bearbeitung von R\u00fcckgaben, Umtauschen, Erstattungen und Kundenservice.<\/li>\n\t<li><strong>Berechtigte Interessen:<\/strong> Verbesserung von Website und Produkten; Betrugs- und Missbrauchspr\u00e4vention; interne Verwaltung und Dokumentation; Analyse der Website-Leistung; sowie (soweit zul\u00e4ssig) Marketing an Bestandskunden oder Lookalike-Audiences. Sie k\u00f6nnen einer Verarbeitung auf Grundlage berechtigter Interessen widersprechen.<\/li>\n\t<li><strong>Rechtliche Verpflichtungen:<\/strong> Einhaltung steuerlicher, buchhalterischer, verbraucherschutz- und datenschutzrechtlicher Anforderungen sowie Beantwortung rechtm\u00e4\u00dfiger beh\u00f6rdlicher Anfragen.<\/li>\n<\/ul>\n<p>Soweit m\u00f6glich, verwenden wir f\u00fcr Analyse- und Werbezwecke statistische oder pseudonymisierte Daten.<\/p>\n\n<p id=\"your-rights\"><strong>4. Welche Rechte haben Sie und wie \u00fcben Sie sie aus?<\/strong><\/p>\n<p>Je nach geltendem Recht k\u00f6nnen Sie insbesondere:<\/p>\n<ul>\n\t<li>Auskunft \u00fcber die bei uns gespeicherten personenbezogenen Daten verlangen und eine Kopie erhalten;<\/li>\n\t<li>unrichtige oder unvollst\u00e4ndige Daten berichtigen lassen;<\/li>\n\t<li>unter bestimmten Voraussetzungen die L\u00f6schung Ihrer Daten verlangen;<\/li>\n\t<li>unter bestimmten Voraussetzungen die Einschr\u00e4nkung der Verarbeitung verlangen;<\/li>\n\t<li>unter bestimmten Voraussetzungen Daten\u00fcbertragbarkeit verlangen;<\/li>\n\t<li>eine Einwilligung verweigern oder widerrufen, soweit wir uns auf Einwilligung st\u00fctzen;<\/li>\n\t<li>der Verarbeitung auf Grundlage berechtigter Interessen widersprechen, einschlie\u00dflich Direktmarketing.<\/li>\n<\/ul>\n<p>Zur Aus\u00fcbung dieser Rechte senden Sie eine E-Mail an <a href=\"mailto:inf&#111;&#64;kr&#121;em&#111;.co&#109;\">info@kryemo.com<\/a>. Bitte geben Sie ausreichend Angaben an, damit wir Sie identifizieren und antworten k\u00f6nnen (z.&nbsp;B. Name, ggf. Bestellnummer und Art Ihres Anliegens).<\/p>\n<p>Bei Bedenken zur Verarbeitung kontaktieren Sie uns bitte zuerst \u2013 wir bem\u00fchen uns um eine L\u00f6sung. Sie k\u00f6nnen sich auch bei der Information Commissioner\u2019s Office (ICO) im Vereinigten K\u00f6nigreich oder bei Ihrer \u00f6rtlichen Aufsichtsbeh\u00f6rde beschweren.<\/p>\n\n<p id=\"third-party\"><strong>5. Websites und Social-Media-Dienste Dritter<\/strong><\/p>\n<p>Unsere Website kann Links zu anderen Websites oder Internetressourcen enthalten. Wenn Sie diese Links anklicken, verlassen Sie unsere Angebote. Wir sind nicht verantwortlich f\u00fcr und kontrollieren nicht die Erhebung, Nutzung oder Offenlegung Ihrer personenbezogenen Daten durch Dritte. Bitte pr\u00fcfen Sie deren Datenschutzhinweise und Bedingungen, bevor Sie Daten angeben.<\/p>\n\n<p id=\"children\"><strong>6. Daten von Minderj\u00e4hrigen<\/strong><\/p>\n<p>Unsere Angebote richten sich grunds\u00e4tzlich nicht an Personen unter 16 Jahren (bzw. unter 13 in bestimmten Rechtsordnungen wie dem Vereinigten K\u00f6nigreich, soweit eigene Einwilligung zul\u00e4ssig ist). Wir erheben wissentlich keine personenbezogenen Daten von Kindern unter diesen Altersgrenzen ohne entsprechende elterliche\/Vormund-Einwilligung. Wenn Sie glauben, dass wir solche Daten versehentlich erhoben haben, kontaktieren Sie uns unter <a href=\"mailto:inf&#111;&#64;k&#114;ye&#109;&#111;.com\">info@kryemo.com<\/a> \u2013 wir werden angemessene Schritte zur L\u00f6schung einleiten.<\/p>\n<p>Altersbeschr\u00e4nkungen f\u00fcr K\u00e4ufe finden Sie auch in unseren <a href=\"\/terms-of-service\/\">Nutzungsbedingungen<\/a>.<\/p>\n\n<p id=\"social\"><strong>7. Social Media, Widgets und offene Foren<\/strong><\/p>\n<p>Unsere Angebote k\u00f6nnen die Nutzung von Social-Media-Diensten (z.&nbsp;B. Facebook, X\/Twitter, Pinterest, Instagram) und Widgets (z.&nbsp;B. \u201eTeilen\u201c-Schaltfl\u00e4chen) erm\u00f6glichen. Diese Funktionen k\u00f6nnen Ihre IP-Adresse erfassen, die besuchte Seite erkennen oder Cookies setzen und sich mit Ihren Social-Media-Konten verbinden. Die Nutzung dieser Dienste unterliegt den Datenschutzrichtlinien der jeweiligen Anbieter. Informationen, die Sie in \u00f6ffentlichen Foren oder sozialen Netzwerken posten, k\u00f6nnen von anderen eingesehen und genutzt werden, ohne dass wir dies einschr\u00e4nken k\u00f6nnen.<\/p>\n\n<p id=\"sharing\"><strong>8. An wen geben wir personenbezogene Daten weiter?<\/strong><\/p>\n<p>Wir k\u00f6nnen Ihre personenbezogenen Daten weitergeben an:<\/p>\n<ul>\n\t<li><strong>Dienstleister<\/strong>, die Daten in unserem Auftrag verarbeiten (z.&nbsp;B. Hosting, IT, Zahlungsabwicklung, Versand\/Fulfillment, R\u00fccksendungen, E-Mail-Versand, Analyse, Kundensupport, Betrugspr\u00e4vention). Wir verpflichten sie, Ihre Daten sicher zu halten und nur f\u00fcr die f\u00fcr uns erbrachten Leistungen zu verwenden.<\/li>\n\t<li><strong>Zahlungsanbieter<\/strong> zur Zahlungsabwicklung und ggf. Bewertung von Zahlungsoptionen. Deren Verarbeitung unterliegt deren eigenen Datenschutzrichtlinien.<\/li>\n\t<li><strong>Versand- und Logistikpartner<\/strong> zur Zustellung Ihrer Bestellungen und Bearbeitung von R\u00fccksendungen.<\/li>\n\t<li><strong>Werbe- und Analysepartner<\/strong> zur Leistungsmessung und (soweit zul\u00e4ssig) zur Ausspielung relevanter Anzeigen.<\/li>\n\t<li><strong>Berufsberater<\/strong> wie Anw\u00e4lte, Buchhalter und Wirtschaftspr\u00fcfer, soweit erforderlich.<\/li>\n\t<li><strong>Gesch\u00e4ftspartner<\/strong>, deren Ware wir verkaufen, soweit zur Auftragserf\u00fcllung n\u00f6tig oder anderweitig gesetzlich\/gem\u00e4\u00df Ihren Pr\u00e4ferenzen zul\u00e4ssig.<\/li>\n\t<li><strong>Beh\u00f6rden oder andere Parteien<\/strong>, soweit gesetzlich erforderlich, zum Schutz von Rechten\/Sicherheit oder zur Untersuchung von Betrug oder Richtlinienverst\u00f6\u00dfen.<\/li>\n\t<li><strong>K\u00e4ufer oder Interessenten<\/strong> im Zusammenhang mit Verkauf, Fusion oder vergleichbarer Unternehmenstransaktion.<\/li>\n\t<li>andere Dritte mit Ihrer Einwilligung.<\/li>\n<\/ul>\n<p><strong>Internationale \u00dcbermittlungen:<\/strong> Einige Empf\u00e4nger k\u00f6nnen au\u00dferhalb des Vereinigten K\u00f6nigreichs, des Europ\u00e4ischen Wirtschaftsraums oder der Schweiz ans\u00e4ssig sein. Soweit erforderlich, nutzen wir geeignete Garantien (z.&nbsp;B. Standardvertragsklauseln oder andere genehmigte Mechanismen). Kontaktieren Sie uns f\u00fcr weitere Informationen.<\/p>\n\n<p id=\"retention\"><strong>9. Wie lange speichern wir Ihre Daten?<\/strong><\/p>\n<p>Wir speichern personenbezogene Daten nur so lange, wie es zur Erf\u00fcllung der Zwecke dieser Datenschutzrichtlinie und zur Einhaltung gesetzlicher Anforderungen erforderlich ist. F\u00fcr unterschiedliche Datens\u00e4tze k\u00f6nnen unterschiedliche Fristen gelten. In der Regel k\u00f6nnen wir personenbezogene Daten bis zu 7 Jahre ab Ihrer letzten Transaktion f\u00fcr steuerliche, buchhalterische und Risikomanagementzwecke speichern. Bei Anfragen, Untersuchungen oder Streitigkeiten kann die Speicherung bis zur Kl\u00e4rung verl\u00e4ngert werden.<\/p>\n<p>Fragen zur Aufbewahrung in Ihrem Einzelfall richten Sie bitte an <a href=\"mailto:i&#110;&#102;o&#64;k&#114;&#121;e&#109;o.&#99;&#111;m\">info@kryemo.com<\/a>.<\/p>\n\n<p id=\"updates\"><strong>10. Aktualisierungen dieser Datenschutzrichtlinie<\/strong><\/p>\n<p>Wir k\u00f6nnen diese Datenschutzrichtlinie von Zeit zu Zeit aktualisieren. Soweit gesetzlich erforderlich, informieren wir angemessen durch Ver\u00f6ffentlichung der aktualisierten Fassung auf dieser Website und\/oder direkte Kontaktaufnahme. Das Datum \u201eZuletzt aktualisiert\u201c oben auf dieser Seite gibt an, wann diese Richtlinie zuletzt \u00fcberarbeitet wurde.<\/p>\n\n<p>Bei Fragen zu dieser Datenschutzrichtlinie kontaktieren Sie uns unter <a href=\"mailto:&#105;nf&#111;&#64;&#107;&#114;y&#101;&#109;&#111;&#46;&#99;&#111;m\">info@kryemo.com<\/a> oder \u00fcber unsere Seite <a href=\"\/contact-us\/\">Kontakt<\/a>. Support-E-Mail: <a href=\"mailto:&#105;&#110;f&#111;&#64;kry&#101;m&#111;.&#99;&#111;m\">info@kryemo.com<\/a>. Betriebsland: China.<\/p>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Zuletzt aktualisiert: Diese Datenschutzrichtlinie erkl\u00e4rt, was mit personenbezogenen Daten geschieht, die Sie uns mitteilen oder die wir \u00fcber Sie erheben, beobachten und\/oder ableiten k\u00f6nnen, wenn Sie unsere Website und damit verbundene Dienste (unsere \u201eAngebote\u201c) nutzen. Bei Fragen kontaktieren Sie uns unter . Diese Datenschutzrichtlinie gilt f\u00fcr personenbezogene Daten, die von oder im Auftrag von verarbeitet [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-20574","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/kryemo.com\/de\/wp-json\/wp\/v2\/pages\/20574","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kryemo.com\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/kryemo.com\/de\/wp-json\/wp\/v2\/types\/page"}],"replies":[{"embeddable":true,"href":"https:\/\/kryemo.com\/de\/wp-json\/wp\/v2\/comments?post=20574"}],"version-history":[{"count":9,"href":"https:\/\/kryemo.com\/de\/wp-json\/wp\/v2\/pages\/20574\/revisions"}],"predecessor-version":[{"id":25928,"href":"https:\/\/kryemo.com\/de\/wp-json\/wp\/v2\/pages\/20574\/revisions\/25928"}],"wp:attachment":[{"href":"https:\/\/kryemo.com\/de\/wp-json\/wp\/v2\/media?parent=20574"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}