{"id":14544,"date":"2026-07-06T06:12:01","date_gmt":"2026-07-06T06:12:01","guid":{"rendered":"https:\/\/jerseys-dev.sizesall.us\/de\/product\/colombia-26-home-kids-jersey\/"},"modified":"2026-08-10T08:27:09","modified_gmt":"2026-08-10T08:27:09","slug":"colombia-26-home-kids-jersey","status":"publish","type":"product","link":"https:\/\/kryemo.com\/de\/product\/colombia-26-home-kids-jersey\/","title":{"rendered":"Adidas Kolumbien Heimtrikot 2026 Kinder"},"content":{"rendered":"<p>Feiern Sie die kolumbianische Fu\u00dfballkultur mit dem Kolumbien 26 Heimtrikot \u2013 ein mutiger Ausdruck nationaler Stolz, entworfen f\u00fcr junge Fans. Inspiriert vom Erbe Kolumbiens, spiegelt das lebendig gef\u00e4rbte Trikot eine unverwechselbare Identit\u00e4t wider.<\/p>\n<p>Entwickelt f\u00fcr Komfort und Leistung, verf\u00fcgt das Trikot \u00fcber die adidas Climacool-Technologie mit Materialien, die Feuchtigkeit ableiten und helfen, Schwei\u00df schnell zu regulieren, f\u00fcr weniger Ablenkungen.<\/p>\n<p>Die strapazierf\u00e4hige Interlock-Konstruktion h\u00e4lt dem Tempo junger Athleten stand, w\u00e4hrend das adidas-Logo und das aufgen\u00e4hte Wappen den Look mit fu\u00dfballerischer Authentizit\u00e4t vervollst\u00e4ndigen. Ein herausragendes St\u00fcck, das Leidenschaft, Spiel und Stolz verbindet \u2013 auf dem Platz oder daneben.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Feiern Sie die kolumbianische Fu\u00dfballkultur mit dem Kolumbien 26 Heimtrikot \u2013 ein mutiger Ausdruck nationaler Stolz, entworfen f\u00fcr junge Fans. Inspiriert vom Erbe Kolumbiens, spiegelt das lebendig gef\u00e4rbte Trikot eine unverwechselbare Identit\u00e4t wider. Entwickelt f\u00fcr Komfort und Leistung, verf\u00fcgt das Trikot \u00fcber die adidas Climacool-Technologie mit Materialien, die Feuchtigkeit ableiten und helfen, Schwei\u00df schnell zu [&hellip;]<\/p>\n","protected":false},"featured_media":23684,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[33],"product_cat":[234],"product_tag":[],"class_list":["post-14544","product","type-product","status-publish","has-post-thumbnail","product_brand-adidas","product_cat-colombia","first","instock","shipping-taxable","purchasable","product-type-variable"],"_links":{"self":[{"href":"https:\/\/kryemo.com\/de\/wp-json\/wp\/v2\/product\/14544","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kryemo.com\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/kryemo.com\/de\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/kryemo.com\/de\/wp-json\/wp\/v2\/comments?post=14544"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/kryemo.com\/de\/wp-json\/wp\/v2\/media\/23684"}],"wp:attachment":[{"href":"https:\/\/kryemo.com\/de\/wp-json\/wp\/v2\/media?parent=14544"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/kryemo.com\/de\/wp-json\/wp\/v2\/product_brand?post=14544"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/kryemo.com\/de\/wp-json\/wp\/v2\/product_cat?post=14544"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/kryemo.com\/de\/wp-json\/wp\/v2\/product_tag?post=14544"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}