{"id":14600,"date":"2026-07-06T06:14:36","date_gmt":"2026-07-06T06:14:36","guid":{"rendered":"https:\/\/jerseys-dev.sizesall.us\/de\/product\/sweden-26-home-jersey\/"},"modified":"2026-08-02T21:14:53","modified_gmt":"2026-08-02T21:14:53","slug":"sweden-26-home-jersey","status":"publish","type":"product","link":"https:\/\/kryemo.com\/de\/product\/sweden-26-home-jersey\/","title":{"rendered":"Adidas Schweden Heimtrikot 26\/27 Herren"},"content":{"rendered":"<div class=\"description_description__laxrX\">\n<div class=\"description_text-content__zFrZJ\">\n<h3 class=\"description_subtitle__5h3_L\">Fu\u00dfballtrikot mit Climacool-Technologie f\u00fcr k\u00fchle, trockene Performance.<\/h3>\n<p class=\"description_margin__cBW26\">Entdecken Sie das Schweden 26 Heimtrikot. Inspiriert von der lebendigen Energie des schwedischen Fu\u00dfballs, pr\u00e4sentiert sich dieses Trikot mit schwedischen G\u00e4nsebl\u00fcmchen und Vintage-Prints, die den Geist des Spiels einfangen. Gefertigt mit der Climacool-Technologie von adidas. Cool. Trocken. Bereit. Climacool leitet Schwei\u00df ab und sorgt f\u00fcr eine k\u00fchle, trockene und ungest\u00f6rte Performance. Dank der Interlock-Konstruktion bietet das Trikot ein angenehmes Tragegef\u00fchl und Langlebigkeit. Der Slim Fit-Schnitt sorgt f\u00fcr eine schlanke Silhouette \u2013 geeignet f\u00fcr den Einsatz auf dem Platz sowie f\u00fcr die Freizeit. Das gestickte adidas-Logo, die 3-Streifen und das SVFF-Wappen verleihen dem Trikot eine authentische Note und unterstreichen Ihre Unterst\u00fctzung f\u00fcr das schwedische Team.<\/p>\n<\/div>\n<div class=\"description_media__QUtul\"><img decoding=\"async\" data-auto-id=\"description-image\" src=\"https:\/\/kryemo.com\/wp-content\/uploads\/2026\/07\/Sweden_26_Home_Jersey_Yellow_JM5814_25_model_3146e688e0-1.jpg\" srcset=\"https:\/\/kryemo.com\/wp-content\/uploads\/2026\/07\/Sweden_26_Home_Jersey_Yellow_JM5814_25_model_ef01c77de3.jpg 320w, https:\/\/kryemo.com\/wp-content\/uploads\/2026\/07\/Sweden_26_Home_Jersey_Yellow_JM5814_25_model_34e2795e2a.jpg 420w, https:\/\/kryemo.com\/wp-content\/uploads\/2026\/07\/Sweden_26_Home_Jersey_Yellow_JM5814_25_model_48cfce4869.jpg 600w, https:\/\/kryemo.com\/wp-content\/uploads\/2026\/07\/Sweden_26_Home_Jersey_Yellow_JM5814_25_model_f929343690.jpg 640w, https:\/\/kryemo.com\/wp-content\/uploads\/2026\/07\/Sweden_26_Home_Jersey_Yellow_JM5814_25_model_9e871fe841.jpg 840w\" sizes=\"(max-width: 320px) 320px, (max-width: 420px) 420px, (max-width: 600px) 600px, (max-width: 640px) 640px, (max-width: 840px) 840px\" alt=\"Gelbes Schweden 26 Heimtrikot\"><\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Fu\u00dfballtrikot mit Climacool-Technologie f\u00fcr k\u00fchle, trockene Performance. Entdecken Sie das Schweden 26 Heimtrikot. Inspiriert von der lebendigen Energie des schwedischen Fu\u00dfballs, pr\u00e4sentiert sich dieses Trikot mit schwedischen G\u00e4nsebl\u00fcmchen und Vintage-Prints, die den Geist des Spiels einfangen. Gefertigt mit der Climacool-Technologie von adidas. Cool. Trocken. Bereit. Climacool leitet Schwei\u00df ab und sorgt f\u00fcr eine k\u00fchle, trockene [&hellip;]<\/p>\n","protected":false},"featured_media":23742,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[33],"product_cat":[386],"product_tag":[],"class_list":["post-14600","product","type-product","status-publish","has-post-thumbnail","product_brand-adidas","product_cat-sweden","first","instock","shipping-taxable","purchasable","product-type-variable"],"_links":{"self":[{"href":"https:\/\/kryemo.com\/de\/wp-json\/wp\/v2\/product\/14600","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kryemo.com\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/kryemo.com\/de\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/kryemo.com\/de\/wp-json\/wp\/v2\/comments?post=14600"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/kryemo.com\/de\/wp-json\/wp\/v2\/media\/23742"}],"wp:attachment":[{"href":"https:\/\/kryemo.com\/de\/wp-json\/wp\/v2\/media?parent=14600"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/kryemo.com\/de\/wp-json\/wp\/v2\/product_brand?post=14600"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/kryemo.com\/de\/wp-json\/wp\/v2\/product_cat?post=14600"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/kryemo.com\/de\/wp-json\/wp\/v2\/product_tag?post=14600"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}