{"id":18846,"date":"2026-07-18T17:47:49","date_gmt":"2026-07-18T17:47:49","guid":{"rendered":"https:\/\/jerseys-dev.sizesall.us\/de\/product\/kids-puma-borussia-dortmund-home-2026-jersey-2\/"},"modified":"2026-08-10T08:27:17","modified_gmt":"2026-08-10T08:27:17","slug":"kids-puma-borussia-dortmund-home-2026-jersey-2","status":"publish","type":"product","link":"https:\/\/kryemo.com\/de\/product\/kids-puma-borussia-dortmund-home-2026-jersey-2\/","title":{"rendered":"Puma Borussia Dortmund Heimtrikot 26\/27 Kinder"},"content":{"rendered":"<ul>\n<li>BVB 26\/27 Heimtrikot f\u00fcr Kinder mit besonderem Sesamstra\u00dfen-Aufdruck auf der R\u00fcckseite.<\/li>\n<li>Von unserem Ausr\u00fcster PUMA<\/li>\n<li>Niedliches Design mit Sesamstra\u00dfen-Charakteren.<\/li>\n<li>100% Polyester<\/li>\n<li>95% recyceltes Polyester dank PUMA&#8217;s RE:FIBRE-Prozess<\/li>\n<\/ul>\n<p>Auch in dieser Saison arbeiten die Sesamstra\u00dfe und der BVB stolz zusammen, um ein fantastisches Design f\u00fcr das BVB-Heimtrikot 2026\/2027 f\u00fcr Kinder zu entwickeln. Die R\u00fcckseite des Trikots erwacht mit einem Hauch von Farbe zum Leben und zeigt eine Reihe Ihrer Lieblingsfiguren aus der Sesamstra\u00dfe: Bert und Ernie, Grover, Elmo und das Kr\u00fcmelmonster. Im Rahmen des &#8220;RE:FIBRE&#8221;-Prozesses hat unser Ausr\u00fcster PUMA 95 % recyceltes Polyester im Material f\u00fcr das diesj\u00e4hrige Heimtrikot verwendet. Dank neuer PUMA-Technologie kann \u00fcbersch\u00fcssiges Polyester nun in neuen Stoff umgewandelt werden, der zur Herstellung der Trikots verwendet wird.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>BVB 26\/27 Heimtrikot f\u00fcr Kinder mit besonderem Sesamstra\u00dfen-Aufdruck auf der R\u00fcckseite. Von unserem Ausr\u00fcster PUMA Niedliches Design mit Sesamstra\u00dfen-Charakteren. 100% Polyester 95% recyceltes Polyester dank PUMA&#8217;s RE:FIBRE-Prozess Auch in dieser Saison arbeiten die Sesamstra\u00dfe und der BVB stolz zusammen, um ein fantastisches Design f\u00fcr das BVB-Heimtrikot 2026\/2027 f\u00fcr Kinder zu entwickeln. Die R\u00fcckseite des Trikots [&hellip;]<\/p>\n","protected":false},"featured_media":24564,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[550],"product_cat":[129],"product_tag":[],"class_list":["post-18846","product","type-product","status-publish","has-post-thumbnail","product_brand-puma","product_cat-borussia-dortmund","first","instock","shipping-taxable","purchasable","product-type-variable"],"_links":{"self":[{"href":"https:\/\/kryemo.com\/de\/wp-json\/wp\/v2\/product\/18846","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kryemo.com\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/kryemo.com\/de\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/kryemo.com\/de\/wp-json\/wp\/v2\/comments?post=18846"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/kryemo.com\/de\/wp-json\/wp\/v2\/media\/24564"}],"wp:attachment":[{"href":"https:\/\/kryemo.com\/de\/wp-json\/wp\/v2\/media?parent=18846"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/kryemo.com\/de\/wp-json\/wp\/v2\/product_brand?post=18846"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/kryemo.com\/de\/wp-json\/wp\/v2\/product_cat?post=18846"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/kryemo.com\/de\/wp-json\/wp\/v2\/product_tag?post=18846"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}