{"id":19454,"date":"2026-07-18T17:54:16","date_gmt":"2026-07-18T17:54:16","guid":{"rendered":"https:\/\/jerseys-dev.sizesall.us\/de\/product\/womens-puma-rb-leipzig-home-2026-jersey\/"},"modified":"2026-08-02T21:47:31","modified_gmt":"2026-08-02T21:47:31","slug":"womens-puma-rb-leipzig-home-2026-jersey","status":"publish","type":"product","link":"https:\/\/kryemo.com\/de\/product\/womens-puma-rb-leipzig-home-2026-jersey\/","title":{"rendered":"Puma RB Leipzig Heimtrikot 26\/27 Damen"},"content":{"rendered":"<p>Made for this! Unser Heimtrikot. Es verbindet uns mit unseren Fans, unserem Stadion. Wir schwitzen darin, k\u00e4mpfen darin, verlieren darin und gewinnen darin. Das neue PUMA Heimtrikot 26\/27 von RB Leipzig f\u00fcr Damen pr\u00e4sentiert sich im ikonischen Rot-Wei\u00df mit weltweit erkennbarem Partner-Branding. Entwickelt f\u00fcr Fans, die es von der Stra\u00dfe bis auf die Trib\u00fcne tragen, ist das Trikot mit dryCELL f\u00fcr H\u00f6chstleistungen gefertigt und wird aus recyceltem Textilabfall im Rahmen des PUMA RE:FIBRE-Programms hergestellt.<\/p>\n<ul>\n<li>RB Leipzig PUMA Heimtrikot 26\/27 f\u00fcr Damen<\/li>\n<li>Passform: Tailored Fit<\/li>\n<li>RB Leipzig Wappen-Patch sowie gedrucktes Red Bull Logo auf der Brust<\/li>\n<li>Gesticktes PUMA Cat Logo auf der rechten Brust und auf den Schultern<\/li>\n<li>&#8220;RB LEIPZIG&#8221; Schriftzug auf der R\u00fcckseite<\/li>\n<li>Flaches authentisches Label am Saum<\/li>\n<li>RE:FIBRE Double-Knit-Gewebekonstruktion, hergestellt aus mindestens 95% recyceltem Textilabfall und anderen gebrauchten Materialien<\/li>\n<li>Mit dryCELL-Performance-Technologie, die Feuchtigkeit vom K\u00f6rper ableitet und Sie beim Training schwei\u00dffrei h\u00e4lt<\/li>\n<li>Material: 100% recyceltes Polyester &#8211; Double Face Jacquard<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Made for this! Unser Heimtrikot. Es verbindet uns mit unseren Fans, unserem Stadion. Wir schwitzen darin, k\u00e4mpfen darin, verlieren darin und gewinnen darin. Das neue PUMA Heimtrikot 26\/27 von RB Leipzig f\u00fcr Damen pr\u00e4sentiert sich im ikonischen Rot-Wei\u00df mit weltweit erkennbarem Partner-Branding. Entwickelt f\u00fcr Fans, die es von der Stra\u00dfe bis auf die Trib\u00fcne tragen, [&hellip;]<\/p>\n","protected":false},"featured_media":24755,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[550],"product_cat":[258],"product_tag":[],"class_list":["post-19454","product","type-product","status-publish","has-post-thumbnail","product_brand-puma","product_cat-rb-leipzig","first","instock","shipping-taxable","purchasable","product-type-variable"],"_links":{"self":[{"href":"https:\/\/kryemo.com\/de\/wp-json\/wp\/v2\/product\/19454","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kryemo.com\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/kryemo.com\/de\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/kryemo.com\/de\/wp-json\/wp\/v2\/comments?post=19454"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/kryemo.com\/de\/wp-json\/wp\/v2\/media\/24755"}],"wp:attachment":[{"href":"https:\/\/kryemo.com\/de\/wp-json\/wp\/v2\/media?parent=19454"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/kryemo.com\/de\/wp-json\/wp\/v2\/product_brand?post=19454"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/kryemo.com\/de\/wp-json\/wp\/v2\/product_cat?post=19454"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/kryemo.com\/de\/wp-json\/wp\/v2\/product_tag?post=19454"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}