{"id":22462,"date":"2026-07-28T02:39:41","date_gmt":"2026-07-28T02:39:41","guid":{"rendered":"https:\/\/jerseys-dev.sizesall.us\/de\/product\/kids-adidas-manchester-united-away-2026-jersey\/"},"modified":"2026-08-10T08:27:30","modified_gmt":"2026-08-10T08:27:30","slug":"kids-adidas-manchester-united-away-2026-jersey","status":"publish","type":"product","link":"https:\/\/kryemo.com\/de\/product\/kids-adidas-manchester-united-away-2026-jersey\/","title":{"rendered":"Adidas Manchester United Ausw\u00e4rtstrikot 26\/27 Kinder"},"content":{"rendered":"<p>Inspiriert vom legend\u00e4ren Trikot von 1988 verbindet das Manchester United Ausw\u00e4rtstrikot 26\/27 Nostalgie mit modernem Design. Die hochwertigen Wellenstreifen symbolisieren den River Irwell und verleihen dem Trikot eine unverwechselbare Optik. Dezente Pr\u00e4gungen und klassische Vereinsdetails runden den Look ab \u2013 perfekt f\u00fcr Spieltag, Schule oder Freizeit.<\/p>\n<p>Der Doppelstrick-Stoff sorgt f\u00fcr Langlebigkeit und ein angenehmes Tragegef\u00fchl, w\u00e4hrend der regul\u00e4re Schnitt volle Bewegungsfreiheit bietet. Der V-Ausschnitt verleiht dem Trikot einen klassischen Fu\u00dfball-Look und macht es zum Must-have f\u00fcr junge Fans, die ihren Verein stilsicher unterst\u00fctzen m\u00f6chten.<\/p>\n<p>Cool. Dry. Ready. Climacool leitet Schwei\u00df ab und sorgt f\u00fcr ein k\u00fchles, trockenes und ablenkungsfreies Tragegef\u00fchl. Ob beim Anfeuern im Stadion oder auf dem Platz \u2013 mit adidas bleiben Kinder auch bei intensiven Aktivit\u00e4ten angenehm k\u00fchl und komfortabel.<\/p>\n","protected":false},"excerpt":{"rendered":"<div id=\"navigation-target-shoe-story\">\n<div class=\"product-story_container__6EPKb\" data-uid=\"statement-2056288\">\n<section class=\"_statement_5zff0_81 _color-theme-white_5zff0_211 has-background\">\n<div class=\"_fill-image_53wku_61 _fit-contain-tablet_53wku_71\" data-auto-id=\"picture\"><picture><source srcset=\"https:\/\/brand.assets.adidas.com\/video\/upload\/global_aclubs_away_manu_football_fw26_launch_rpdp_banner_statement_1_d_9509398344.mp4\" media=\"(min-width: 960px)\" \/><source srcset=\"https:\/\/brand.assets.adidas.com\/image\/upload\/global_aclubs_away_manu_football_fw26_launch_rpdp_banner_statement_1_t_058dfa75d6.jpg\" media=\"(min-width: 768px)\" \/><source srcset=\"https:\/\/brand.assets.adidas.com\/image\/upload\/global_aclubs_away_manu_football_fw26_launch_rpdp_banner_statement_1_m_224da60eb2.jpg\" media=\"(max-width: 767px)\" \/><img decoding=\"async\" src=\"https:\/\/kryemo.com\/wp-content\/uploads\/2026\/07\/global_aclubs_away_manu_football_fw26_launch_rpdp_banner_statement_1_d_950939834_e23d8ea6de.mp4\" alt=\"Visual mit m\u00e4nnlichen und weiblichen Manchester United Spielern im neuen Manchester United 26\/27 Ausw\u00e4rtstrikot\" \/><\/picture><\/div>\n<\/section>\n<\/div>\n<div class=\"product-story_container__6EPKb\" data-uid=\"statement-2056132\">\n<section class=\"_statement_5zff0_81 color-theme-black has-background\">\n<div class=\"_fill-image_53wku_61 _fit-contain-tablet_53wku_71\" data-auto-id=\"picture\"><picture><source srcset=\"https:\/\/brand.assets.adidas.com\/image\/upload\/global_aclubs_away_manu_football_fw26_launch_rpdp_banner_statement_2_d_31c3b64677.jpg\" media=\"(min-width: 960px)\" \/><source srcset=\"https:\/\/brand.assets.adidas.com\/image\/upload\/global_aclubs_away_manu_football_fw26_launch_rpdp_banner_statement_2_t_db2f93b4f2.jpg\" media=\"(min-width: 768px)\" \/><source srcset=\"https:\/\/brand.assets.adidas.com\/image\/upload\/global_aclubs_away_manu_football_fw26_launch_rpdp_banner_statement_2_m_213b8709ac.jpg\" media=\"(max-width: 767px)\" \/><img decoding=\"async\" src=\"https:\/\/kryemo.com\/wp-content\/uploads\/2026\/07\/global_aclubs_away_arsenal_football_fw26_launch_rpdp_banner_statement_2_d_f85ebc_d0c6778c80-scaled.jpg\" alt=\"Ein wei\u00dfer Hintergrund mit einem schmalen, vertikalen, hellgelben Rand auf der linken und rechten Seite.\" \/><\/picture><\/div>\n<div class=\"grid-row no-gutters _content-row_5zff0_86 _has-background-media_5zff0_90\" style=\"pointer-events: none;\">\n<div class=\"col--mb-s-6\">\n<div class=\"_content_5zff0_86\">\n<h2 class=\"_title_5zff0_141\">Man Utd 26\/27 Ausw\u00e4rtstrikot<\/h2>\n<p class=\"_summary_5zff0_165\" data-auto-id=\"summary\">Die blauen Ausw\u00e4rtstrikots von Manchester United sind ikonisch. Das Design dieser Saison setzt auf wellenf\u00f6rmige Ton-in-Ton-Streifen mit klassischen roten und wei\u00dfen Akzenten, verwurzelt in der DNA des Vereins, und das adidas Originals Logo verleiht dem Ganzen einen stylischen Touch. Entwickelt f\u00fcr den \u00dcbergang vom Spieltag in den Alltag.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/section>\n<\/div>\n<\/div>\n","protected":false},"featured_media":25713,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[33],"product_cat":[191],"product_tag":[],"class_list":["post-22462","product","type-product","status-publish","has-post-thumbnail","product_brand-adidas","product_cat-manchester-united","first","instock","shipping-taxable","purchasable","product-type-variable"],"_links":{"self":[{"href":"https:\/\/kryemo.com\/de\/wp-json\/wp\/v2\/product\/22462","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kryemo.com\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/kryemo.com\/de\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/kryemo.com\/de\/wp-json\/wp\/v2\/comments?post=22462"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/kryemo.com\/de\/wp-json\/wp\/v2\/media\/25713"}],"wp:attachment":[{"href":"https:\/\/kryemo.com\/de\/wp-json\/wp\/v2\/media?parent=22462"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/kryemo.com\/de\/wp-json\/wp\/v2\/product_brand?post=22462"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/kryemo.com\/de\/wp-json\/wp\/v2\/product_cat?post=22462"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/kryemo.com\/de\/wp-json\/wp\/v2\/product_tag?post=22462"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}